{"id":161,"count":2,"description":"","link":"https:\/\/lawwwing.com\/en\/partner-category\/audiovisual-content\/","name":"Audiovisual","slug":"audiovisual-content","taxonomy":"categoria-de-partners","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/lawwwing.com\/en\/wp-json\/wp\/v2\/categoria-de-partners\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lawwwing.com\/en\/wp-json\/wp\/v2\/categoria-de-partners"}],"about":[{"href":"https:\/\/lawwwing.com\/en\/wp-json\/wp\/v2\/taxonomies\/categoria-de-partners"}],"wp:post_type":[{"href":"https:\/\/lawwwing.com\/en\/wp-json\/wp\/v2\/directorio-partners?categoria-de-partners=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}